{"id":398,"date":"2018-07-24T09:00:23","date_gmt":"2018-07-24T12:00:23","guid":{"rendered":"http:\/\/farmaciabiguacu.com.br\/blog\/?p=398"},"modified":"2025-12-17T15:25:03","modified_gmt":"2025-12-17T18:25:03","slug":"saude-mental-x-comportamento-compulsivo","status":"publish","type":"post","link":"http:\/\/farmaciabiguacu.com.br\/blog\/saude-mental-x-comportamento-compulsivo\/","title":{"rendered":"SA\u00daDE MENTAL X COMPORTAMENTO COMPULSIVO"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Quando o assunto \u00e9 compulsividade, geralmente lembramos das situa\u00e7\u00f5es que envolvem subst\u00e2ncias como \u00e1lcool, drogas e cigarros. O que costumamos n\u00e3o levar em considera\u00e7\u00e3o \u00e9 que existem muitos outros comportamentos que s\u00e3o compulsivos e que est\u00e3o ligados \u00e0 outros fatores. Comprar de forma exagerada, comer descontroladamente, repetir movimentos sem controle e sem sentido, lavar as m\u00e3os em demasia, tudo isso podem ser comportamentos compulsivos e que devem ser avaliados por um profissional competente. Comportamentos assim geralmente est\u00e3o ligados a uma press\u00e3o interna que o indiv\u00edduo n\u00e3o consegue controlar e que lhe d\u00e1 uma sensa\u00e7\u00e3o de felicidade e prazer no in\u00edcio, mas depois faz a pessoa se sentir culpada e triste consigo mesma. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Recentemente, o uso inadequado e o tempo gasto com computadores e internet tamb\u00e9m tem contribu\u00eddo para quest\u00f5es desse tipo. Pessoas com dificuldades de relacionamento social ou com quadros depressivos acabam passando longos per\u00edodos imersos em ambientes virtuais e muitas vezes isso reflete negativamente at\u00e9 no ambiente de trabalho, onde elas continuam a usar por exemplo as redes sociais e os jogos, esquecendo da vida real.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Mas cuidado, nem sempre comer uma barra de chocolates ou abusar no almo\u00e7o de domingo \u00e9 uma caracter\u00edstica de comportamento compulsivo. Vale sempre a regra que falamos aqui: <\/span><b>buscar aux\u00edlio profissional. <\/b><span style=\"font-weight: 400;\">Sempre converse com o profissional de sa\u00fade da sua confian\u00e7a e n\u00e3o saia por a\u00ed achando que tem este ou aquele problema. Mas se voc\u00ea observar alguns comportamentos diferentes e falta de controle em rela\u00e7\u00e3o \u00e0 eles, nestes casos \u00e9 importante sim buscar ajuda.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Hoje em dia, o apelo ao corpo escultural, a necessidade de postar \u201ccoisas novas\u201d nas redes sociais, o desejo pelo alcance de uma \u00f3tima vida financeira \u201cpra ontem\u201d refletem em um comportamento mais imediatista e exibicionista, aumentando as cobran\u00e7as que as pessoas fazem consigo mesmas. Isso &nbsp;estimula comportamentos ansiosos e muitas vezes compulsivos levando as pessoas a buscarem outras fontes de prazer para descontar a frustra\u00e7\u00e3o di\u00e1ria como comer descontroladamente, comprar sem necessidade, usar subst\u00e2ncias entorpecentes, entre outros.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"> &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Mas, a compuls\u00e3o tem tratamento? Para as pessoas compulsivas o primeiro passo \u00e9 reconhecer e admitir o problema: \u00e9 necess\u00e1rio aceitar que algo est\u00e1 errado. Existem grupos onde v\u00e1rias pessoas que enfrentam o mesmo problema se re\u00fanem e compartilham suas experi\u00eancias, dificuldades e tamb\u00e9m como est\u00e3o buscando melhorar. Buscar ajuda profissional \u00e9 o segundo passo: busque aux\u00edlio com m\u00e9dicos e psic\u00f3logos para entender as causas e encontrar a melhor forma de tratamento. Lembre-se que voc\u00ea n\u00e3o est\u00e1 sozinho e converse com seus amigos e familiares. <\/span><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-399\" src=\"http:\/\/farmaciabiguacu.com.br\/blog\/wp-content\/uploads\/2018\/07\/2018.07.24-Blog-1024x724.jpg\" alt=\"\" width=\"1024\" height=\"724\" srcset=\"http:\/\/farmaciabiguacu.com.br\/blog\/wp-content\/uploads\/2018\/07\/2018.07.24-Blog-1024x724.jpg 1024w, http:\/\/farmaciabiguacu.com.br\/blog\/wp-content\/uploads\/2018\/07\/2018.07.24-Blog-300x212.jpg 300w, http:\/\/farmaciabiguacu.com.br\/blog\/wp-content\/uploads\/2018\/07\/2018.07.24-Blog-768x543.jpg 768w, http:\/\/farmaciabiguacu.com.br\/blog\/wp-content\/uploads\/2018\/07\/2018.07.24-Blog.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Quando o assunto \u00e9 compulsividade, geralmente lembramos das situa\u00e7\u00f5es que envolvem subst\u00e2ncias como \u00e1lcool, drogas e cigarros. O que costumamos n\u00e3o levar em considera\u00e7\u00e3o \u00e9 que existem muitos outros comportamentos &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[227,33,149],"tags":[59,13,64,58,132,84],"class_list":["post-398","post","type-post","status-publish","format-standard","hentry","category-bem-estar","category-cuidados-pessoais","category-saude-mental","tag-bem-estar","tag-cuidados","tag-cuidados-pessoais","tag-saude","tag-saude-mental","tag-vida"],"_links":{"self":[{"href":"http:\/\/farmaciabiguacu.com.br\/blog\/wp-json\/wp\/v2\/posts\/398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/farmaciabiguacu.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/farmaciabiguacu.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/farmaciabiguacu.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/farmaciabiguacu.com.br\/blog\/wp-json\/wp\/v2\/comments?post=398"}],"version-history":[{"count":2,"href":"http:\/\/farmaciabiguacu.com.br\/blog\/wp-json\/wp\/v2\/posts\/398\/revisions"}],"predecessor-version":[{"id":811,"href":"http:\/\/farmaciabiguacu.com.br\/blog\/wp-json\/wp\/v2\/posts\/398\/revisions\/811"}],"wp:attachment":[{"href":"http:\/\/farmaciabiguacu.com.br\/blog\/wp-json\/wp\/v2\/media?parent=398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/farmaciabiguacu.com.br\/blog\/wp-json\/wp\/v2\/categories?post=398"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/farmaciabiguacu.com.br\/blog\/wp-json\/wp\/v2\/tags?post=398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}